{"id":1225,"date":"2019-06-20T16:39:27","date_gmt":"2019-06-20T16:39:27","guid":{"rendered":"https:\/\/cargonizer.ca\/cargonizer\/?page_id=1225"},"modified":"2024-05-28T19:33:02","modified_gmt":"2024-05-28T19:33:02","slug":"standard-trading-conditions","status":"publish","type":"page","link":"https:\/\/cargonizer.ca\/fr\/standard-trading-conditions\/","title":{"rendered":"CONDITIONS GENERALES DE VENTE"},"content":{"rendered":"<div id=\"pl-gb1225-6a570ae14fc56\"  class=\"panel-layout\" ><div id=\"pg-gb1225-6a570ae14fc56-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb1225-6a570ae14fc56-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb1225-6a570ae14fc56-0-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child\" data-index=\"0\" ><div class=\"panel-widget-style panel-widget-style-for-gb1225-6a570ae14fc56-0-0-0\" ><div class=\"textwidget\"><h3 style=\"color: #1f435d\"><strong>CONDITIONS GENERALES DE VENTE<\/strong><\/h3>\n<\/div><\/div><\/div><div id=\"panel-gb1225-6a570ae14fc56-0-0-1\" class=\"so-panel widget widget_media_image panel-last-child\" data-index=\"1\" ><div class=\"panel-widget-style panel-widget-style-for-gb1225-6a570ae14fc56-0-0-1\" ><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"379\" src=\"https:\/\/cargonizer.ca\/wp-content\/uploads\/2019\/09\/Standard_Trading_Conditions-1-1024x379.png\" class=\"image wp-image-1882  attachment-large size-large\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/cargonizer.ca\/wp-content\/uploads\/2019\/09\/Standard_Trading_Conditions-1-1024x379.png 1024w, https:\/\/cargonizer.ca\/wp-content\/uploads\/2019\/09\/Standard_Trading_Conditions-1-600x222.png 600w, https:\/\/cargonizer.ca\/wp-content\/uploads\/2019\/09\/Standard_Trading_Conditions-1-300x111.png 300w, https:\/\/cargonizer.ca\/wp-content\/uploads\/2019\/09\/Standard_Trading_Conditions-1-768x284.png 768w, https:\/\/cargonizer.ca\/wp-content\/uploads\/2019\/09\/Standard_Trading_Conditions-1.png 1772w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><div id=\"pg-gb1225-6a570ae14fc56-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb1225-6a570ae14fc56-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb1225-6a570ae14fc56-1-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"2\" ><div class=\"textwidget\"><p align=\"justify\">CargoNizer offre ses services sur la base des pr\u00e9sentes conditions qui s'appliquent \u00e0 toutes les activit\u00e9s de la soci\u00e9t\u00e9 en mati\u00e8re d'organisation du transport ou de fourniture de services connexes, tels que, mais sans s'y limiter, l'entreposage et tout autre type de services logistiques.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"pg-gb1225-6a570ae14fc56-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb1225-6a570ae14fc56-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb1225-6a570ae14fc56-2-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"3\" ><div class=\"textwidget\"><h3 style=\"font-weight: 400;text-align: center\"><strong>CONDITIONS G\u00c9N\u00c9RALES DE VENTE<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<\/div><\/div><\/div><\/div><div id=\"pg-gb1225-6a570ae14fc56-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb1225-6a570ae14fc56-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb1225-6a570ae14fc56-3-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"textwidget\"><ol>\n<li><strong>R\u00d4LE DU TRANSITAIRE (la \u00abSoci\u00e9t\u00e9\u00bb)<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">La Soci\u00e9t\u00e9 rend ses services en vertu des pr\u00e9sentes conditions. Celles-ci\ns\u2019appliquent \u00e0 l\u2019ensemble des activit\u00e9s que m\u00e8ne la Soci\u00e9t\u00e9 dans la prise\nde dispositions pour le transport ou la prestation de services connexes tels\nque, mais sans s\u2019y limiter, l\u2019entreposage et tout autre type de services logistiques\napparent\u00e9s. La Soci\u00e9t\u00e9 peut fournir ses services soit \u00e0 titre d\u2019entrepreneur,\nsoit \u00e0 titre de mandataire.\nLa Soci\u00e9t\u00e9 agit comme mandataire du Client, sauf<\/p>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px\">\n<li style=\"text-align: justify\">lorsqu\u2019elle \u00e9met un\ndocument de transport ou un enregistrement \u00e9lectronique attestant de son\nobligation de livrer les marchandises, ou<\/li>\n<li style=\"text-align: justify\" class=\"translation-block\">dans la mesure o\u00f9 elle\neffectue, avec ses propres employ\u00e9s et \u00e9quipements, la manutention des\nmarchandises dans le cadre de l\u2019ex\u00e9cution de tout service, auxquels cas\nelle agit comme entrepreneur.\nLes pr\u00e9sentes conditions r\u00e9gissent les droits et les obligations du Client et\nde la Soci\u00e9t\u00e9, que celle-ci agisse \u00e0 titre d\u2019entrepreneur ou \u00e0 titre de mandataire.\nAux fins de d\u00e9terminer les droits ou obligations de la Soci\u00e9t\u00e9 en vertu des\npr\u00e9sentes conditions, le terme \u00ab Client \u00bb inclut la partie qui donne les\ninstructions, l\u2019exp\u00e9diteur, le consignataire et le propri\u00e9taire des marchandises.\nNonobstant ce qui pr\u00e9c\u00e8de, les conseils sont destin\u00e9s uniquement\nau Client et ne doivent \u00eatre fournis \u00e0 aucune autre partie sans le consentement\n\u00e9crit pr\u00e9alable de la Soci\u00e9t\u00e9. Les conseils et les renseignements fournis\n\u00e0 titre gracieux qui ne sont pas li\u00e9s aux instructions accept\u00e9es par la\nSoci\u00e9t\u00e9 n\u2019engagent pas sa responsabilit\u00e9, ni celle d\u00e9coulant de la n\u00e9gligence.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li><strong>R\u00c9CLAMATIONS CONTRE D\u2019AUTRES PARTIES<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Les pr\u00e9sentes conditions s\u2019appliquent \u00e9galement \u00e0 toute r\u00e9clamation faite\ncontre un employ\u00e9, un mandataire ou un entrepreneur ind\u00e9pendant engag\u00e9\npar la Soci\u00e9t\u00e9 pour ex\u00e9cuter tout transport ou service connexe concernant\nles marchandises du Client, qu\u2019une telle r\u00e9clamation soit fond\u00e9e ou non sur\nle r\u00e9gime de la responsabilit\u00e9 contractuelle ou celui de la responsabilit\u00e9\nextra-contractuelle. La responsabilit\u00e9 globale de la Soci\u00e9t\u00e9 et de l\u2019une ou\nl\u2019autre des parties mentionn\u00e9es ci-dessus ne pourra pas exc\u00e9der les limites\nde responsabilit\u00e9 pr\u00e9vues aux pr\u00e9sentes conditions. Aux fins de l\u2019application\nde cette disposition, la Soci\u00e9t\u00e9 agit comme mandataire de ces parties\net celles-ci peuvent ratifier ce mandat a posteriori.<\/p>\n<ol start=\"3\">\n<li><strong>R\u00d4LE EN TANT QUE MANDATAIRE<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">\u00c0 titre de mandataire, la Soci\u00e9t\u00e9 agit uniquement au nom du Client\nlorsqu\u2019elle retient les services de tiers selon les modalit\u00e9s et conditions\nusuelles en vertu desquelles ces derniers offrent ces services de transport,\nd\u2019entreposage, d\u2019emballage ou de manutention de toutes marchandises, ou\ntout autre service connexe. Des liens contractuels directs sont en cons\u00e9quence\n\u00e9tablis entre le Client et le fournisseur de ces services, de sorte\nque le Client peut en exiger l\u2019ex\u00e9cution \u00e0 titre de mandant et ce, que l\u2019identit\u00e9\ndu Client apparaisse ou non au contrat. La Soci\u00e9t\u00e9 doit fournir une\npreuve de tout contrat conclu au nom du client lorsque celui-ci lui en fait la\ndemande.<\/p>\n<ol start=\"4\">\n<li><strong>R\u00d4LE \u00c0 TITRE D\u2019ENTREPRENEUR<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px\">Lorsque le Client le demande, la Soci\u00e9t\u00e9 peut :<\/p>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px\">\n<li style=\"text-align: justify\">\u00e9mettre un document de transport ou un document \u00e9lectronique\nen vertu duquel elle s\u2019engage, \u00e0 titre d\u2019entrepreneur, \u00e0 proc\u00e9der\nau transport de marchandises d\u00e9finies; ou<\/li>\n<li style=\"text-align: justify\">garantir par \u00e9crit l\u2019ex\u00e9cution ad\u00e9quate des modalit\u00e9s de tout contrat\nconclu entre le Client et un tiers dont la Soci\u00e9t\u00e9 a retenu les\nservices au nom du Client.<\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Lorsque la Soci\u00e9t\u00e9 \u00e9met un document de transport ou un document \u00e9lectronique,\nou qu\u2019elle fournit une garantie, ses droits et ses obligations sont\nr\u00e9gis par les conditions sp\u00e9cifiques qui y sont stipul\u00e9es, lesquelles s\u2019ajoutent\n\u00e0 celles \u00e9nonc\u00e9es aux pr\u00e9sentes. Dans tous les cas, la Soci\u00e9t\u00e9 n\u2019est\nresponsable que dans la m\u00eame mesure o\u00f9 l\u2019est le tiers qui effectue le transport\nou le service garanti, et cette responsabilit\u00e9 peut \u00eatre limit\u00e9e en vertu\ndes conditions selon lesquelles ce tiers offre habituellement ses services.\nEn cas d\u2019incompatibilit\u00e9 entre les pr\u00e9sentes conditions et les conditions\nsp\u00e9cifiques, ces derni\u00e8res l\u2019emportent.<\/p>\n<ol start=\"5\">\n<li><strong>SERVICES N\u00c9CESSITANT DES DISPOSITIONS SP\u00c9CIALES<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Dans un d\u00e9lai raisonnable avant le moment pr\u00e9vu pour l\u2019entreposage ou le\ntransport des marchandises, le Client doit fournir \u00e0 la Soci\u00e9t\u00e9 des instructions \u00e9crites lorsqu\u2019il lui demande de :<\/p>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>prendre les dispositions n\u00e9cessaires pour le d\u00e9part et l\u2019arriv\u00e9e\ndes marchandises avant des dates pr\u00e9cises;<\/li>\n<li>prendre les dispositions n\u00e9cessaires pour que les marchandises\nsoient transport\u00e9es, entrepos\u00e9es ou manutentionn\u00e9es s\u00e9par\u00e9ment\nde d\u2019autres marchandises;<\/li>\n<li>prendre les dispositions n\u00e9cessaires pour le transport de\nmarchandises pouvant contaminer ou affecter d\u2019autres marchandises,\nou pouvant faire l\u2019objet d\u2019une infestation par la vermine ou\nles insectes ou favoriser une telle infestation;<\/li>\n<li>faire une d\u00e9claration de valeur ou d\u2019int\u00e9r\u00eat particulier \u00e0 la livraison\n\u00e0 tout transporteur ou terminal;<\/li>\n<li>donner comme directive aux transporteurs ou aux responsables\nde la livraison de conserver les marchandises jusqu\u2019au paiement\nd\u2019un certain montant ou jusqu\u2019\u00e0 la remise d\u2019un document;<\/li>\n<li>prendre les dispositions n\u00e9cessaires pour le transport de\nmarchandises pr\u00e9sentant une valeur inhabituellement \u00e9lev\u00e9e,\nbiens de luxe, devises, titres ou valeurs n\u00e9gociables de toute\nnature, pierres ou m\u00e9taux pr\u00e9cieux, antiquit\u00e9s ou oeuvres d\u2019art,\nd\u00e9pouilles humaines, animaux ou plantes, ou autre cargaison de\nsemblable nature.<\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">La Soci\u00e9t\u00e9 doit aviser promptement le Client par tout moyen de communication\nutilis\u00e9 dans le cours normal des affaires, lorsqu\u2019elle n\u2019accepte pas,\npour quelque raison que ce soit, de telles instructions. Si, apr\u00e8s r\u00e9ception\nd\u2019un tel avis, il d\u00e9cide malgr\u00e9 tout de continuer d\u2019utiliser les services de la\nSoci\u00e9t\u00e9 pour le transport envisag\u00e9, le Client assume tous les risques reli\u00e9s\n\u00e0 l\u2019inex\u00e9cution de ces instructions que ceux-ci d\u00e9coulent ou non de la n\u00e9gligence\nde la Soci\u00e9t\u00e9.<\/p>\n<ol start=\"6\">\n<li><strong>OBLIGATIONS G\u00c9N\u00c9RALES DE LA SOCI\u00c9T\u00c9<\/strong><\/li>\n<\/ol>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>La Soci\u00e9t\u00e9 doit faire preuve de diligence raisonnable dans l\u2019ex\u00e9cution\ndes obligations qui lui incombent, y compris dans le choix de tiers\nfournissant tout service au nom du Client et dans la communication\ndes instructions<\/li>\n<li>Apr\u00e8s avoir re\u00e7u les instructions du Client, la Soci\u00e9t\u00e9 doit prendre les\ndispositions n\u00e9cessaires pour le transport et tout service connexe dans un d\u00e9lai raisonnable.<\/li>\n<li>La Soci\u00e9t\u00e9 peut, sans avis pr\u00e9alable au Client, d\u00e9roger \u00e0 toute instruction\nde ce dernier si elle a des motifs raisonnables pour ce faire. Elle doit toutefois agir dans l\u2019int\u00e9r\u00eat du Client et l\u2019informer dans les meilleurs d\u00e9lais de ses actions et de tous frais additionnels en d\u00e9coulant.<\/li>\n<\/ol>\n<ol start=\"7\">\n<li><strong>OBLIGATIONS G\u00c9N\u00c9RALES DU CLIENT<\/strong><\/li>\n<\/ol>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>Le Client est r\u00e9put\u00e9 \u00eatre comp\u00e9tent et poss\u00e9der une connaissance\nraisonnable des facteurs ayant une incidence sur la conduite de ses\naffaires, y compris les modalit\u00e9s d\u2019achat et de vente, la n\u00e9cessit\u00e9 de\nsouscrire une assurance et l\u2019\u00e9tendue de la protection disponible pour\nles types de marchandises faisant l\u2019objet de l\u2019exp\u00e9dition, le besoin de\npr\u00e9server et de conserver la documentation, les pr\u00e9cautions n\u00e9cessaires\npour pr\u00e9venir la transmission de virus lors de communications\n\u00e9lectroniques, la n\u00e9cessit\u00e9 de traiter en toute confidentialit\u00e9 l\u2019information\nrelative aux marchandises \u00e0 valeur \u00e9lev\u00e9e et tout autre sujet connexe.<\/li>\n<li>Le Client garantit que tous les renseignements qu\u2019il fournit ou qui sont\nfournis en son nom, sous quelque forme que ce soit, concernant le caract\u00e8re\ng\u00e9n\u00e9ral et dangereux des marchandises, description, code \u00e0\nbarres, marques, num\u00e9ro, poids, volume et quantit\u00e9, \u00e9taient pr\u00e9cis et\ncomplets au moment o\u00f9 les marchandises ont \u00e9t\u00e9 prises en charge par\nla Soci\u00e9t\u00e9 ou tout tiers dont elle a retenu les services. Le Client s\u2019engage\nde plus, sur demande de la Soci\u00e9t\u00e9, \u00e0 fournir une confirmation\nind\u00e9pendante de ces informations.<\/li>\n<\/ol>\n<ol start=\"8\">\n<li><strong>OBLIGATIONS DU CLIENT \u00c0 L\u2019\u00c9GARD DES MARCHANDISES EMBALL\u00c9ES ET CONTENEURIS\u00c9ES<\/strong><\/li>\n<\/ol>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>Sauf lorsque la Soci\u00e9t\u00e9 a accept\u00e9 des instructions concernant la pr\u00e9paration,\nl\u2019emballage, l\u2019arrimage, l\u2019\u00e9tiquetage ou le marquage des\nmarchandises, le Client garantit, pour toute marchandise, qu\u2019elle est\ncorrectement et suffisamment pr\u00e9par\u00e9e, emball\u00e9e, arrim\u00e9e, \u00e9tiquet\u00e9e\net\/ou marqu\u00e9e et que la pr\u00e9paration, l\u2019emballage, l\u2019arrimage, l\u2019\u00e9tiquetage\net le marquage sont adapt\u00e9s aux caract\u00e9ristiques des marchandises\net se pr\u00eatent aux op\u00e9rations ou transactions dont elles peuvent faire l\u2019objet.<\/li>\n<li>Sauf si la Soci\u00e9t\u00e9 a accept\u00e9 les instructions de prendre des dispositions ou d\u2019entreprendre le chargement d\u2019une unit\u00e9 de transport avec ses employ\u00e9s, le Client garantit que :\n<ul style=\"list-style-type: lower-roman;padding-left: 20px\">\n<li>l\u2019unit\u00e9 de transport est charg\u00e9e correctement et de fa\u00e7on comp\u00e9tente;<\/li>\n<li>les marchandises sont aptes au transport dans ou sur l\u2019unit\u00e9 de transport;<br \/>et<\/li>\n<li>l\u2019unit\u00e9 de transport est dans un \u00e9tat ad\u00e9quat pour le transport des\nmarchandises qui y sont charg\u00e9es (sauf dans la mesure o\u00f9 la\nSoci\u00e9t\u00e9 aurait confirm\u00e9 que l\u2019unit\u00e9 de transport est ad\u00e9quate).<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<ol start=\"9\">\n<li><strong>SOUMISSIONS ET FACTURATION<\/strong><\/li>\n<\/ol>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>La Soci\u00e9t\u00e9 n\u2019assume pas le r\u00f4le d\u2019entrepreneur en fournissant une\nsoumission \u00e0 prix forfaitaire, ni en facturant un montant dont la diff\u00e9rence\nentre les sommes vers\u00e9es aux tiers retenus pour mettre en\noeuvre les instructions du Client et le prix forfaitaire repr\u00e9sente le profit\nbrut de la Soci\u00e9t\u00e9 pour ses services. Un Client convient que la Soci\u00e9t\u00e9\nest un mandataire au sens donn\u00e9 \u00e0 l\u2019article 1, lorsqu\u2019il :\n<ul style=\"list-style-type: lower-roman;padding-left: 20px\">\n<li>accepte une soumission de prix forfaitaire, ou<\/li>\n<li>ne s\u2019oppose pas dans les trente jours suivant la r\u00e9ception de la facture \u00e0 ce que la Soci\u00e9t\u00e9 exige un prix forfaitaire pour ses services.<\/li>\n<\/ul>\n<\/li>\n<li>Les soumissions sont donn\u00e9es sous condition d\u2019acceptation imm\u00e9diate\net peuvent \u00eatre retir\u00e9es ou r\u00e9vis\u00e9es. \u00c0 moins qu\u2019il n\u2019en soit pr\u00e9vu autrement dans la soumission, la Soci\u00e9t\u00e9 est libre, apr\u00e8s acceptation, de r\u00e9viser les prix ou les frais, moyennant un avis \u00e0 cet effet lorsque les\nchangements ne d\u00e9pendent pas de sa volont\u00e9 notamment lorsqu\u2019ils portent sur les taux de change, taux de fret, aux suppl\u00e9ments impos\u00e9s\npar les transporteurs ou tout autre frais applicable aux marchandises.<\/li>\n<\/ol>\n<ol start=\"10\">\n<li><strong>EXP\u00c9DITION CONTRE REMBOURSEMENT (C.R.)<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Lorsque les marchandises sont accept\u00e9es ou trait\u00e9es avec instructions de\npercevoir du consignataire ou de toute autre personne, le fret, les droits,\ntaxes ou autres frais, le Client demeure responsable de ceux-ci s\u2019ils ne sont\npas acquitt\u00e9s par le consignataire ou par cette autre personne d\u00e8s qu\u2019ils\nsont dus.<\/p>\n<ol start=\"11\">\n<li><strong>CHANGEMENT DE CIRCONSTANCES\/D\u00c9FAUT DE PRENDRE LIVRAISON<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">La Soci\u00e9t\u00e9 doit prendre les moyens raisonnables afin d\u2019obtenir de nouvelles\ninstructions du Client lorsque des \u00e9v\u00e9nements, tel que le d\u00e9faut par ce\ndernier de prendre livraison, surviennent et affectent l\u2019ex\u00e9cution du mandat.\nSi, pour quelque raison que ce soit, la Soci\u00e9t\u00e9 ne re\u00e7oit pas d\u2019instructions\nen temps opportun, elle peut :<\/p>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>entreposer les marchandises aux risques et aux frais exclusifs du Client;\n<p style=\"padding-left: 0px\">ou<\/p>\n<\/li>\n<li>vendre les marchandises imm\u00e9diatement et sans autre avis, et conserver tout produit net au nom du Client; ou<\/li>\n<li>autoriser tout tiers \u00e0 cesser le transport des marchandises et \u00e0 les\nmettre, en tout ou en partie, \u00e0 la disposition du Client \u00e0 un endroit\nraisonnable compte tenu des circonstances.<\/li>\n<\/ol>\n<ol start=\"12\">\n<li><strong>MARCHANDISES DANGEREUSES<\/strong><\/li>\n<\/ol>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>Le Client s\u2019engage \u00e0 ne pas pr\u00e9senter \u00e0 des fins de transport des\nmarchandises qui sont dangereuses, inflammables ou radioactives ou\nde nature dommageable, sans fournir \u00e0 la Soci\u00e9t\u00e9 tous les d\u00e9tails les\nconcernant. Le Client s\u2019engage \u00e0 marquer les marchandises ainsi que\nla surface ext\u00e9rieure des emballages ou des conteneurs dans lesquels\nelles pourraient \u00eatre plac\u00e9es conform\u00e9ment aux lois et r\u00e8glements\napplicables en cours de transport. Pour les marchandises dont le lieu\nde livraison se trouve au Canada, le Client garantit de plus que les\nmarchandises, leur emballage et leur marquage sont conformes \u00e0 tous\n\u00e9gard aux dispositions pr\u00e9vues dans la loi et les r\u00e8glements r\u00e9gissant\nle transport de marchandises dangereuses.<\/li>\n<li>Le Client qui ne satisfait pas aux exigences \u00e9nonc\u00e9es au paragraphe \u2018A\u2019 est tenu d\u2019indemniser la Soci\u00e9t\u00e9 de toute perte et de tout dommage ou frais d\u00e9coulant du fait qu\u2019il a ainsi pr\u00e9sent\u00e9 des marchandises \u00e0 des fins de transport ou de manutention par ou pour le compte de tiers engag\u00e9s par la Soci\u00e9t\u00e9.<\/li>\n<li>Les marchandises qui, de l\u2019avis de la Soci\u00e9t\u00e9 ou de la personne qui en a la garde ou la possession, sont ou peuvent devenir dangereuses ou constituer un danger, peuvent, en tout lieu et \u00e0 tout moment, \u00eatre d\u00e9charg\u00e9es, d\u00e9truites ou rendues inoffensives, sans que la responsabilit\u00e9 de la Soci\u00e9t\u00e9 ne soit engag\u00e9e.<\/li>\n<\/ol>\n<ol start=\"13\">\n<li><strong>ASSURANCE<\/strong><\/li>\n<\/ol>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>Le Client doit fournir \u00e0 la Soci\u00e9t\u00e9 des instructions \u00e9crites dans un d\u00e9lai\nraisonnable avant la pr\u00e9sentation des marchandises aux fins d\u2019entreposage\nou de transport afin qu\u2019elle souscrive une assurance. La Soci\u00e9t\u00e9 peut ex\u00e9cuter ces instructions en d\u00e9clarant la valeur des\nmarchandises en vertu d\u2019une police ouverte sur facult\u00e9s prise par elle et, sur demande, fournir un certificat ou une attestation, ou autre\npreuve d\u2019assurance. La protection des marchandises ainsi d\u00e9clar\u00e9es est assujettie aux modalit\u00e9s de la police. La Soci\u00e9t\u00e9 n\u2019est pas responsable si le Client, pour quelque raison que ce soit, n\u2019obtient pas indemnisation, en tout ou en partie, de l\u2019assureur en vertu de ladite police, et ce, m\u00eame si la prime demand\u00e9e par l\u2019assureur est diff\u00e9rente des frais exig\u00e9s du Client par la Soci\u00e9t\u00e9.<\/li>\n<li>Si la protection en vertu de la police ouverte sur facult\u00e9s n\u2019est pas satisfaisante,\nla Soci\u00e9t\u00e9 recommandera un courtier d\u2019assurances en mesure d\u2019offrir une assurance adapt\u00e9e aux besoins du Client. Une fois\ncette recommandation faite, la Soci\u00e9t\u00e9 n\u2019aura aucune autre obligation en ce qui a trait \u00e0 l\u2019assurance ni n\u2019aura aucune responsabilit\u00e9 en cas de perte ou dommage aux marchandises en cours de transport ou d\u2019entreposage, qui auraient pu \u00eatre couverts par l\u2019assurance sur les marchandises, qu\u2019une telle perte ou un tel dommage aient \u00e9t\u00e9 caus\u00e9s par sa n\u00e9gligence ou par une violation des pr\u00e9sentes conditions ou autrement.<\/li>\n<\/ol>\n<ol start=\"14\">\n<li><strong>AVIS DE R\u00c9CLAMATIONS<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Le Client, pour lui-m\u00eame et au nom du propri\u00e9taire des marchandises, doit aviser la Soci\u00e9t\u00e9 par \u00e9crit de toute r\u00e9clamation :<\/p>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>en cas de perte ou dommage aux marchandises, dans les 7 jours suivant la fin du transport;<\/li>\n<li>en cas de retard ou de d\u00e9faut de livraison, dans les 45 jours suivant la date \u00e0 laquelle les marchandises auraient d\u00fb \u00eatre livr\u00e9es;<\/li>\n<li>dans tous les autres cas, dans les 45 jours suivant l\u2019\u00e9v\u00e9nement donnant lieu \u00e0 la r\u00e9clamation.<\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Si le pr\u00e9judice donnant lieu \u00e0 la r\u00e9clamation n\u2019a pu \u00eatre d\u00e9couvert malgr\u00e9\nune diligence raisonnable au cours de la p\u00e9riode applicable, le Client doit\nsur-le-champ fournir un avis \u00e0 cet effet apr\u00e8s avoir re\u00e7u l\u2019information concernant\nles \u00e9v\u00e9nements pouvant donner lieu \u00e0 une r\u00e9clamation. Tout d\u00e9faut de\nfournir l\u2019avis en vertu des pr\u00e9sentes entra\u00eene le rejet de la r\u00e9clamation et\naucune action ne peut \u00eatre intent\u00e9e contre la Soci\u00e9t\u00e9 pour celle-ci.<\/p>\n<ol start=\"15\">\n<li><strong>LIMITATION DE RESPONSABILIT\u00c9<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">L\u2019indemnit\u00e9 \u00e0 l\u2019\u00e9gard de toute r\u00e9clamation pour laquelle la Soci\u00e9t\u00e9 est\nresponsable ne peut en aucun cas exc\u00e9der 3000 CAD .\nSans pr\u00e9judice \u00e0 toute autre disposition \u00e9nonc\u00e9e aux pr\u00e9sentes ou\n\u00e0 toute autre d\u00e9fense dont la Soci\u00e9t\u00e9 pourrait se pr\u00e9valoir, celle-ci n\u2019est en\naucun cas responsable envers le Client ou le propri\u00e9taire pour :<\/p>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>des pertes indirectes, y compris les pertes de march\u00e9s, sauf dans la mesure pr\u00e9vue au paragraphe \u2018b\u2019;<\/li>\n<li>pertes, dommages ou pertes indirectes caus\u00e9s par un retard ou une d\u00e9rogation relativement au transport des marchandises, pour un montant sup\u00e9rieur \u00e0 deux fois la diff\u00e9rence entre les frais factur\u00e9s par la Soci\u00e9t\u00e9 et les montants pay\u00e9s par celle-ci \u00e0 des tiers pour le transport ou autre service reli\u00e9 \u00e0 ces marchandises;<\/li>\n<li>une somme sup\u00e9rieure au maximum recouvrable .<\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">La Soci\u00e9t\u00e9 peut accepter d\u2019augmenter ces limites de responsabilit\u00e9 sur demande \u00e9crite du Client et moyennant paiement par celui-ci des frais additionnels qui en d\u00e9coulent. Le Client peut obtenir les d\u00e9tails de ces frais aupr\u00e8s de la Soci\u00e9t\u00e9.\u00a0<\/p>\n<ol start=\"16\">\n<li><strong>INDEMNISATION<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Le Client doit indemniser la Soci\u00e9t\u00e9 de toutes sommes d\u00e9coulant ou reli\u00e9es aux actes pos\u00e9s par celle ci pour tout service couvert par les pr\u00e9sentes conditions, dont celles concernant les droits, taxes, paiements, amendes, d\u00e9penses, pertes, r\u00e9clamations, responsabilit\u00e9s et, notamment, les frais portuaires, d\u2019entreposage, de terminaux ou de surestarie de m\u00eame que de toute obligation d\u2019indemniser toute personne pour des r\u00e9clamations faites \u00e0 celle-ci par le Client ou le propri\u00e9taire des marchandises<\/p>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>pour lesquelles la Soci\u00e9t\u00e9 peut \u00eatre tenue responsable, \u00e0 moins qu\u2019elles ne d\u00e9coulent de sa n\u00e9gligence ou d\u2019un manquement \u00e0 ses obligations; ou<\/li>\n<li>qui exc\u00e8dent l\u2019\u00e9tendue de la responsabilit\u00e9 de la Soci\u00e9t\u00e9 en vertu des pr\u00e9sentes.<\/li>\n<\/ol>\n<ol start=\"17\">\n<li><strong>COMPENSATION ET DEMANDE RECONVENTIONNELLE<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Le Client doit payer \u00e0 la Soci\u00e9t\u00e9, en esp\u00e8ces, ou tel qu\u2019autrement convenu,\ntoute cr\u00e9ance d\u00e8s qu\u2019elle est exigible, sans retenue, r\u00e9duction ou report au\nmotif de quelque r\u00e9clamation, demande reconventionnelle ou compensation que ce soit.<\/p>\n<ol start=\"18\">\n<li><strong>DROIT DE R\u00c9TENTION ET PRIVIL\u00c8GE<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Les marchandises (et les documents s\u2019y rapportant) sont assujetties \u00e0 un\nprivil\u00e8ge sp\u00e9cial et g\u00e9n\u00e9ral ainsi qu\u2019\u00e0 un droit de r\u00e9tention pour les sommes dues, soit relativement \u00e0 ces marchandises, soit pour le solde de tout compte sp\u00e9cifique ou g\u00e9n\u00e9ral, ou pour d\u2019autres sommes, qu\u2019elles soient ou\nnon alors dues \u00e0 la Soci\u00e9t\u00e9 par le Client, l\u2019exp\u00e9diteur, le consignataire ou le\npropri\u00e9taire des marchandises. La Soci\u00e9t\u00e9 peut, \u00e0 son enti\u00e8re discr\u00e9tion, proc\u00e9der \u00e0 la vente des marchandises de gr\u00e9 \u00e0 gr\u00e9 ou autrement si les\nsommes qui lui sont dues ne sont pas acquitt\u00e9es dans les 10 jours suivant\nl\u2019envoi d\u2019un avis d\u2019exercice de ses droits aux personnes concern\u00e9es par tout moyen de communication raisonnable dans les circonstances. Le produit net de la vente est imput\u00e9 aux sommes dues. La Soci\u00e9t\u00e9 n\u2019est responsable d\u2019aucune insuffisance ou diminution de la valeur r\u00e9alis\u00e9e et le Client n\u2019est pas lib\u00e9r\u00e9 de ses obligations du seul fait de la vente des marchandises.<\/p>\n<ol start=\"19\">\n<li><strong>PRESCRIPTION<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Sauf convention contraire, la Soci\u00e9t\u00e9 est d\u00e9gag\u00e9e de toute responsabilit\u00e9 en vertu des pr\u00e9sentes conditions \u00e0 moins qu\u2019une action ne soit intent\u00e9e dans les 9 mois suivant :<\/p>\n<ol style=\"list-style-type: lower-alpha;padding-left: 60px;text-align: justify\">\n<li>la date de livraison des marchandises, pour les r\u00e9clamations pour dommages \u00e0 celles-ci; ou<\/li>\n<li>la date \u00e0 laquelle les marchandises auraient d\u00fb \u00eatre livr\u00e9es, pour les r\u00e9clamations pour retard dans leur livraison ou pour leur perte.<\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Dans les cas o\u00f9 les pertes ou les dommages ne concernent pas les marchandises, le d\u00e9lai de 9 mois court \u00e0 compter du moment o\u00f9 l\u2019acte ou\nl\u2019omission de la Soci\u00e9t\u00e9 a donn\u00e9 lieu \u00e0 la r\u00e9clamation.<\/p>\n<ol start=\"20\">\n<li><strong>R\u00c9MUN\u00c9RATION COUTUMI\u00c8RE RE\u00c7UE DE TIERS<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">La Soci\u00e9t\u00e9 a le droit de recevoir et de conserver tous frais de courtage pay\u00e9s par les transporteurs, toutes commissions, toutes r\u00e9mun\u00e9rations concernant la confection de la documentation, tous profits sur le change et toutes autres r\u00e9mun\u00e9rations pay\u00e9es par des tiers, comme il est \u00e9tabli par la coutume dans l\u2019industrie.\u00a0<\/p>\n<ol start=\"21\">\n<li><strong>LOI APPLICABLE ET COMP\u00c9TENCE<\/strong><\/li>\n<\/ol>\n<p style=\"padding-left: 40px;text-align: justify\">Les pr\u00e9sentes conditions sont r\u00e9gies par les lois du Canada et de la province canadienne dans laquelle la Soci\u00e9t\u00e9 a sa principale place d\u2019affaires. En acceptant les services fournis en vertu de ces conditions, le Client acquiesce et se soumet de mani\u00e8re irr\u00e9vocable \u00e0 la comp\u00e9tence exclusive des tribunaux de cette province et de la Cour f\u00e9d\u00e9rale du Canada.<\/p>\n<p style=\"padding-left: 40px;text-align: justify\">Les parties conviennent que lorsqu\u2019elles utilisent des communications \u00e9lectroniques pour effectuer des transactions d\u2019affaires, en tout ou en partie, celles-ci ont la port\u00e9e juridique que leur conf\u00e8rent les dispositions, en autant qu\u2019elles soient applicables, de la Loi uniforme sur le commerce \u00e9lectronique, telle qu\u2019approuv\u00e9e par la Conf\u00e9rence pour l\u2019harmonisation des lois au Canada<\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Standard Trading Conditions CargoNizer offers its services on the basis of these conditions that\u00a0apply to all activities of the Company in arranging transportation or providing\u00a0related services, such as, but not limited to, warehousing and any other kind of logistics services.<\/p>","protected":false},"author":3,"featured_media":1228,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1225","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cargonizer.ca\/fr\/wp-json\/wp\/v2\/pages\/1225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cargonizer.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cargonizer.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cargonizer.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cargonizer.ca\/fr\/wp-json\/wp\/v2\/comments?post=1225"}],"version-history":[{"count":43,"href":"https:\/\/cargonizer.ca\/fr\/wp-json\/wp\/v2\/pages\/1225\/revisions"}],"predecessor-version":[{"id":2037,"href":"https:\/\/cargonizer.ca\/fr\/wp-json\/wp\/v2\/pages\/1225\/revisions\/2037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cargonizer.ca\/fr\/wp-json\/wp\/v2\/media\/1228"}],"wp:attachment":[{"href":"https:\/\/cargonizer.ca\/fr\/wp-json\/wp\/v2\/media?parent=1225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}